{"id":539,"count":13,"description":"<p dir=\"auto\">D\u00e9couvrez le monde fascinant de la culture de vos propres champignons psych\u00e9d\u00e9liques gr\u00e2ce \u00e0 nos kits de culture de champignons magiques de haute qualit\u00e9. Parfaits pour les d\u00e9butants comme pour les cultivateurs exp\u00e9riment\u00e9s, ces kits rendent la culture des vari\u00e9t\u00e9s de Psilocybe Cubensis simple et gratifiante. Avec tout ce dont vous avez besoin, du myc\u00e9lium activ\u00e9 aux instructions faciles \u00e0 suivre, vous pouvez profiter d'une exp\u00e9rience de culture sans faille et explorer les effets uniques des diff\u00e9rentes souches \u00e0 la maison.<\/p>","link":"https:\/\/www.tatanka.nl\/fr\/shroomshop\/magic-mushroom-grow-kits\/","name":"Kits de culture de champignons magiques","slug":"magic-mushroom-grow-kits","taxonomy":"product_cat","parent":515,"meta":[],"menu_order":86,"_links":{"self":[{"href":"https:\/\/www.tatanka.nl\/fr\/wp-json\/wp\/v2\/product_cat\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tatanka.nl\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.tatanka.nl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.tatanka.nl\/fr\/wp-json\/wp\/v2\/product_cat\/515"}],"wp:post_type":[{"href":"https:\/\/www.tatanka.nl\/fr\/wp-json\/wp\/v2\/product?product_cat=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}